{"id":243,"count":1,"description":"","link":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/","name":"pub mambo no one","slug":"pub-mambo-no-one","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pub mambo no one Archive - Rostock entdecken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pub mambo no one Archive - Rostock entdecken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/\" \/>\n<meta property=\"og:site_name\" content=\"Rostock entdecken\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rostock-entdecken.de\\\/index.php\\\/tag\\\/pub-mambo-no-one\\\/\",\"url\":\"https:\\\/\\\/rostock-entdecken.de\\\/index.php\\\/tag\\\/pub-mambo-no-one\\\/\",\"name\":\"pub mambo no one Archive - Rostock entdecken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rostock-entdecken.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rostock-entdecken.de\\\/index.php\\\/tag\\\/pub-mambo-no-one\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rostock-entdecken.de\\\/index.php\\\/tag\\\/pub-mambo-no-one\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rostock-entdecken.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pub mambo no one\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rostock-entdecken.de\\\/#website\",\"url\":\"https:\\\/\\\/rostock-entdecken.de\\\/\",\"name\":\"Rostock entdecken\",\"description\":\"Ein Ausbildungsprojekt des medien colleg rostock\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rostock-entdecken.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pub mambo no one Archive - Rostock entdecken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/","og_locale":"de_DE","og_type":"article","og_title":"pub mambo no one Archive - Rostock entdecken","og_url":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/","og_site_name":"Rostock entdecken","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/","url":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/","name":"pub mambo no one Archive - Rostock entdecken","isPartOf":{"@id":"https:\/\/rostock-entdecken.de\/#website"},"breadcrumb":{"@id":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/rostock-entdecken.de\/index.php\/tag\/pub-mambo-no-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rostock-entdecken.de\/"},{"@type":"ListItem","position":2,"name":"pub mambo no one"}]},{"@type":"WebSite","@id":"https:\/\/rostock-entdecken.de\/#website","url":"https:\/\/rostock-entdecken.de\/","name":"Rostock entdecken","description":"Ein Ausbildungsprojekt des medien colleg rostock","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rostock-entdecken.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/rostock-entdecken.de\/index.php\/wp-json\/wp\/v2\/tags\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rostock-entdecken.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rostock-entdecken.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rostock-entdecken.de\/index.php\/wp-json\/wp\/v2\/posts?tags=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}